{"id":2929,"count":0,"description":"","link":"http:\/\/www.imedtehnika.com\/blog\/tag\/en-standard-hydraulic-hose-4f91-001e27\/","name":"EN Standard Hydraulic Hose","slug":"en-standard-hydraulic-hose-4f91-001e27","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.imedtehnika.com\/blog\/wp-json\/wp\/v2\/tags\/2929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.imedtehnika.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.imedtehnika.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.imedtehnika.com\/blog\/wp-json\/wp\/v2\/posts?tags=2929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}